{"id":295,"date":"2016-01-26T23:48:58","date_gmt":"2016-01-26T23:48:58","guid":{"rendered":"http:\/\/www.ad-particles.com\/es\/?page_id=295"},"modified":"2021-04-15T17:31:04","modified_gmt":"2021-04-15T17:31:04","slug":"aviso-legal-y-politica-de-privacidad","status":"publish","type":"page","link":"http:\/\/www.ad-particles.com\/es\/aviso-legal-y-politica-de-privacidad\/","title":{"rendered":"Aviso Legal y pol\u00edtica de privacidad"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"295\" class=\"elementor elementor-295\">\n\t\t\t\t\t\t<div class=\"elementor-inner\">\n\t\t\t\t<div class=\"elementor-section-wrap\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1e8b64a9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1e8b64a9\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6ac98807\" data-id=\"6ac98807\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3e851035 elementor-widget elementor-widget-text-editor\" data-id=\"3e851035\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<ul><li><p class=\"oneComWebmail-MsoNormal\" align=\"center\"><span style=\"color: #e46e36;\">LEY DE LOS SERVICIOS DE LA SOCIEDAD DE LA INFORMACI\u00d3N (LSSI)<\/span><\/p><p class=\"oneComWebmail-MsoNormal\">ADVANCED DISPERSED PARTICLES S.L, responsable del sitio web, en adelante RESPONSABLE, pone a disposici\u00f3n de los usuarios el presente documento, con el que pretende dar cumplimiento a las obligaciones dispuestas en la Ley 34\/2002, de 11 de julio, de Servicios de la Sociedad de la Informaci\u00f3n y de Comercio Electr\u00f3nico (LSSICE), BOE N \u00ba 166, as\u00ed como informar a todos los usuarios del sitio web respecto a cu\u00e1les son las condiciones de uso.<\/p><p class=\"oneComWebmail-MsoNormal\">\u00a0<\/p><p class=\"oneComWebmail-MsoNormal\">Toda persona que acceda a este sitio web asume el papel de usuario, comprometi\u00e9ndose a la observancia y cumplimiento riguroso de las disposiciones aqu\u00ed dispuestas, as\u00ed como a cualquier otra disposici\u00f3n legal que fuera de aplicaci\u00f3n.<\/p><p class=\"oneComWebmail-MsoNormal\">\u00a0<\/p><p class=\"oneComWebmail-MsoNormal\">ADVANCED DISPERSED PARTICLES S.L se reserva el derecho de modificar cualquier tipo de informaci\u00f3n que pudiera aparecer en el sitio web, sin que exista obligaci\u00f3n de preavisar o poner en conocimiento de los usuarios dichas obligaciones, entendi\u00e9ndose como suficiente con la publicaci\u00f3n en el sitio web de ADVANCED DISPERSED PARTICLES S.L.<\/p><p class=\"oneComWebmail-MsoNormal\" align=\"center\"><span style=\"color: #e46e36;\">1. DATOS IDENTIFICATIVOS<\/span><\/p><p class=\"oneComWebmail-MsoNormal\">Nombre de dominio: www.adpcosmetics.es www.ad-particles.com<\/p><p class=\"oneComWebmail-MsoNormal\">Nombre comercial: ADVANCED DISPERSED PARTICLES S.L<\/p><p class=\"oneComWebmail-MsoNormal\">Denominaci\u00f3n social: ADVANCED DISPERSED PARTICLES S.L<\/p><p class=\"oneComWebmail-MsoNormal\">NIF: B86299211<\/p><p class=\"oneComWebmail-MsoNormal\">Domicilio social: CALLE DEL ORO45 NAVE 14 , 28770 COLMENAR VIEJO (MADRID)<\/p><p class=\"oneComWebmail-MsoNormal\">Tel\u00e9fono: 910136640<\/p><p class=\"oneComWebmail-MsoNormal\">e-mail: info@ad-particles.com<\/p><p class=\"oneComWebmail-MsoNormal\">Inscrita en el Registro (Mercantil \/ P\u00fablico): Datos Registrales BORME, Registro Mercantil de MADRID T 35816 , F 22, S 8, H M525027, I\/A 1<\/p><p class=\"oneComWebmail-MsoNormal\" align=\"center\"><span style=\"color: #e46e36;\">2. DERECHOS DE PROPIEDAD INTELECTUAL E INDUSTRIAL<\/span><\/p><p class=\"oneComWebmail-MsoNormal\">El sitio web, incluyendo a t\u00edtulo enunciativo pero no limitativo su programaci\u00f3n, edici\u00f3n, compilaci\u00f3n y dem\u00e1s elementos necesarios para su funcionamiento, los dise\u00f1os, logotipos, texto y\/o gr\u00e1ficos, son propiedad del RESPONSABLE o, si es el caso, dispone de licencia o autorizaci\u00f3n expresa por parte de los autores. Todos los contenidos del sitio web se encuentran debidamente protegidos por la normativa de propiedad intelectual e industrial, as\u00ed como inscritos en los registros p\u00fablicos correspondientes. Independientemente de la finalidad para la que fueran destinados, la reproducci\u00f3n total o parcial, uso, explotaci\u00f3n, distribuci\u00f3n y comercializaci\u00f3n, requiere en todo caso de la autorizaci\u00f3n escrita previa por parte del RESPONSABLE. Cualquier uso no autorizado previamente se considera un incumplimiento grave de los derechos de propiedad intelectual o industrial del autor.<\/p><p class=\"oneComWebmail-MsoNormal\">\u00a0<\/p><p class=\"oneComWebmail-MsoNormal\">Los dise\u00f1os, logotipos, texto y\/o gr\u00e1ficos ajenos al RESPONSABLE y que pudieran aparecer en el sitio web, pertenecen a sus respectivos propietarios, siendo ellos mismos responsables de cualquier posible controversia que pudiera suscitarse respecto a los mismos. El RESPONSABLE autoriza expresamente a que terceros puedan redirigir directamente a los contenidos concretos del sitio web, y en todo caso redirigir al sitio web principal de www.adpcosmetics.es www.ad-particles.com.<\/p><p class=\"oneComWebmail-MsoNormal\">\u00a0<\/p><p class=\"oneComWebmail-MsoNormal\">El RESPONSABLE reconoce a favor de sus titulares los correspondientes derechos de propiedad intelectual e industrial, no implicando su sola menci\u00f3n o aparici\u00f3n en el sitio web la existencia de derechos o responsabilidad alguna sobre los mismos, como tampoco respaldo, patrocinio o recomendaci\u00f3n por parte del mismo.<\/p><p class=\"oneComWebmail-MsoNormal\">\u00a0<\/p><p class=\"oneComWebmail-MsoNormal\">Para realizar cualquier tipo de observaci\u00f3n respecto a posibles incumplimientos de los derechos de propiedad intelectual o industrial, as\u00ed como sobre cualquiera de los contenidos del sitio web, puede hacerlo a trav\u00e9s del correo electr\u00f3nico info@ad-particles.com.<\/p><p class=\"oneComWebmail-MsoNormal\">\u00a0<\/p><p class=\"oneComWebmail-MsoNormal\" align=\"center\"><span style=\"color: #e46e36;\">3. EXENCI\u00d3N DE RESPONSABILIDADES<\/span><\/p><p class=\"oneComWebmail-MsoNormal\">El RESPONSABLE se exime de cualquier tipo de responsabilidad derivada de la informaci\u00f3n publicada en su sitio web siempre que esta informaci\u00f3n haya sido manipulada o introducida por un tercero ajeno al mismo.<\/p><p class=\"oneComWebmail-MsoNormal\">\u00a0<\/p><p class=\"oneComWebmail-MsoNormal\">Uso de Cookies<\/p><p class=\"oneComWebmail-MsoNormal\">Este sitio web puede utilizar cookies t\u00e9cnicas (peque\u00f1os archivos de informaci\u00f3n que el servidor env\u00eda al ordenador de quien accede a la p\u00e1gina) para llevar a cabo determinadas funciones que son consideradas imprescindibles para el correcto funcionamiento y visualizaci\u00f3n del sitio. Las cookies utilizadas tienen, en todo caso, car\u00e1cter temporal, con la \u00fanica finalidad de hacer m\u00e1s eficaz la navegaci\u00f3n, y desaparecen al terminar la sesi\u00f3n del usuario. En ning\u00fan caso, estas cookies proporcionan por s\u00ed mismas datos de car\u00e1cter personal y no se utilizar\u00e1n para la recogida de los mismos.<\/p><p class=\"oneComWebmail-MsoNormal\">\u00a0<\/p><p class=\"oneComWebmail-MsoNormal\">Mediante el uso de cookies tambi\u00e9n es posible que el servidor donde se encuentra la web reconozca el navegador utilizado por el usuario con la finalidad de que la navegaci\u00f3n sea m\u00e1s sencilla, permitiendo, por ejemplo, el acceso de los usuarios que se hayan registrado previamente a las \u00e1reas, servicios, promociones o concursos reservados exclusivamente a ellos sin tener que registrarse en cada visita. Tambi\u00e9n se pueden utilizar para medir la audiencia, par\u00e1metros de tr\u00e1fico, controlar el progreso y n\u00famero de entradas, etc, siendo en estos casos cookies prescindibles t\u00e9cnicamente pero beneficiosas para el usuario. Este sitio web no instalar\u00e1 cookies prescindibles sin el consentimiento previo del usuario.<\/p><p class=\"oneComWebmail-MsoNormal\">\u00a0<\/p><p class=\"oneComWebmail-MsoNormal\">El usuario tiene la posibilidad de configurar su navegador para ser alertado de la recepci\u00f3n de cookies y para impedir su instalaci\u00f3n en su equipo. Por favor, consulte las instrucciones de su navegador para ampliar esta informaci\u00f3n.<\/p><p class=\"oneComWebmail-MsoNormal\">\u00a0<\/p><p class=\"oneComWebmail-MsoNormal\" align=\"center\">Pol\u00edtica de enlaces<\/p><p class=\"oneComWebmail-MsoNormal\">Desde el sitio web, es posible que se redirija a contenidos de terceros sitios web. Dado que el RESPONSABLE no puede controlar siempre los contenidos introducidos por los terceros en sus respectivos sitios web, no asume ning\u00fan tipo de responsabilidad respecto a dichos contenidos. En todo caso, proceder\u00e1 a la retirada inmediata de cualquier contenido que pudiera contravenir la legislaci\u00f3n nacional o internacional, la moral o el orden p\u00fablico, procediendo a la retirada inmediata de la redirecci\u00f3n a dicho sitio web, poniendo en conocimiento de las autoridades competentes el contenido en cuesti\u00f3n.<\/p><p class=\"oneComWebmail-MsoNormal\">\u00a0<\/p><p class=\"oneComWebmail-MsoNormal\">El RESPONSABLE no se hace responsable de la informaci\u00f3n y contenidos almacenados, a t\u00edtulo enunciativo pero no limitativo, en foros, chats, generadores de blogs, comentarios, redes sociales o cualquier otro medio que permita a terceros publicar contenidos de forma independiente en la p\u00e1gina web del RESPONSABLE. Sin embargo, y en cumplimiento de lo dispuesto en los art\u00edculos 11 y 16 de la LSSICE, se pone a disposici\u00f3n de todos los usuarios, autoridades y fuerzas de seguridad,colaborando de forma activa en la retirada o, en su caso, bloqueo de todos aquellos contenidos que puedan afectar o contravenir la legislaci\u00f3n nacional o internacional, los derechos de terceros o la moral y el orden p\u00fablico. En caso de que el usuario considere que existe en el sitio web alg\u00fan contenido que pudiera ser susceptible de esta clasificaci\u00f3n, se ruega lo notifique de forma inmediata al administrador del sitio web.<\/p><p class=\"oneComWebmail-MsoNormal\">\u00a0<\/p><p class=\"oneComWebmail-MsoNormal\">Este sitio web ha sido revisado y probado para que funcione correctamente. En principio, puede garantizarse el correcto funcionamiento los 365 d\u00edas del a\u00f1o, 24 horas al d\u00eda. Sin embargo, el RESPONSABLE no descarta la posibilidad de que existan ciertos errores de programaci\u00f3n, o que acontezcan causas de fuerza mayor, cat\u00e1strofes naturales, huelgas o circunstancias semejantes que hagan imposible el acceso a la p\u00e1gina web.<\/p><p class=\"oneComWebmail-MsoNormal\">\u00a0<\/p><p class=\"oneComWebmail-MsoNormal\" align=\"center\">Direcciones IP<\/p><p class=\"oneComWebmail-MsoNormal\">Los servidores del sitio web podr\u00e1n detectar de manera autom\u00e1tica la direcci\u00f3n IP y el nombre de dominio utilizados por el usuario. Una direcci\u00f3n IP es un n\u00famero asignado autom\u00e1ticamente a un ordenador cuando \u00e9ste se conecta a Internet. Toda esta informaci\u00f3n es registrada en un fichero de actividad del servidor debidamente inscrito que permite el posterior procesamiento de los datos con el fin de obtener mediciones \u00fanicamente estad\u00edsticas que permitan conocer el n\u00famero de impresiones de p\u00e1ginas, el n\u00famero de visitas realizadas a los servidores web, el orden de visitas, el punto de acceso, etc.<\/p><p class=\"oneComWebmail-MsoNormal\">\u00a0<\/p><p class=\"oneComWebmail-MsoNormal\" align=\"center\"><span style=\"color: #e46e36;\">4. LEY APLICABLE Y JURISDICCI\u00d3N<\/span><\/p><p class=\"oneComWebmail-MsoNormal\">Para la resoluci\u00f3n de todas las controversias o cuestiones relacionadas con el presente sitio web o de las actividades en \u00e9l desarrolladas, ser\u00e1 de aplicaci\u00f3n la legislaci\u00f3n espa\u00f1ola, a la que se someten expresamente las partes, siendo competentes para la resoluci\u00f3n de todos los conflictos derivados o relacionados con su uso los Juzgados y Tribunales m\u00e1s cercanos a COLMENAR VIEJO.<\/p><\/li><\/ul>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>LEY DE LOS SERVICIOS DE LA SOCIEDAD DE LA INFORMACI\u00d3N (LSSI) ADVANCED DISPERSED PARTICLES S.L, responsable del sitio web, en adelante RESPONSABLE, pone a disposici\u00f3n de los usuarios el presente documento, con el que pretende dar cumplimiento a las obligaciones dispuestas en la Ley 34\/2002, de 11 de julio, de Servicios de la Sociedad de &hellip; <a href=\"http:\/\/www.ad-particles.com\/es\/aviso-legal-y-politica-de-privacidad\/\" class=\"more-link\">Continue reading<span class=\"screen-reader-text\"> &#8220;Aviso Legal y pol\u00edtica de privacidad&#8221;<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":4,"comment_status":"closed","ping_status":"closed","template":"cookies-policy.php","meta":{"_mi_skip_tracking":false},"_links":{"self":[{"href":"http:\/\/www.ad-particles.com\/es\/wp-json\/wp\/v2\/pages\/295"}],"collection":[{"href":"http:\/\/www.ad-particles.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"http:\/\/www.ad-particles.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"http:\/\/www.ad-particles.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/www.ad-particles.com\/es\/wp-json\/wp\/v2\/comments?post=295"}],"version-history":[{"count":6,"href":"http:\/\/www.ad-particles.com\/es\/wp-json\/wp\/v2\/pages\/295\/revisions"}],"predecessor-version":[{"id":531,"href":"http:\/\/www.ad-particles.com\/es\/wp-json\/wp\/v2\/pages\/295\/revisions\/531"}],"wp:attachment":[{"href":"http:\/\/www.ad-particles.com\/es\/wp-json\/wp\/v2\/media?parent=295"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}